{"id":12886,"date":"2025-07-24T14:20:55","date_gmt":"2025-07-24T14:20:55","guid":{"rendered":"https:\/\/rolling-legal.com\/?page_id=12886"},"modified":"2026-04-16T10:07:29","modified_gmt":"2026-04-16T10:07:29","slug":"integracoes","status":"publish","type":"page","link":"https:\/\/rolling-legal.com\/es\/integracoes\/","title":{"rendered":"Integra\u00e7\u00f5es"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"12886\" class=\"elementor elementor-12886\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d737cbc e-flex e-con-boxed e-con e-parent\" data-id=\"d737cbc\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c7e4bbb elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"c7e4bbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Conecte-se e simplifique!<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8b57d6 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b8b57d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Centralize comunica\u00e7\u00f5es, documentos e informa\u00e7\u00e3o relevante numa s\u00f3 plataforma, sem obrigar a equipa a mudar a forma como j\u00e1 trabalha. O Rolling Legal ajuda a reduzir contexto disperso, melhorar a organiza\u00e7\u00e3o e aumentar o controlo da opera\u00e7\u00e3o jur\u00eddica.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05d1091 e-flex e-con-boxed e-con e-parent\" data-id=\"05d1091\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8779477 e-con-full e-flex e-con e-child\" data-id=\"8779477\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dcbfab5 elementor-widget elementor-widget-heading\" data-id=\"dcbfab5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Integra\u00e7\u00f5es que poupam tempo<\/br>\ne aumentam produtividade.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b735387 e-con-full e-flex e-con e-child\" data-id=\"b735387\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-50489da elementor-widget elementor-widget-image\" data-id=\"50489da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1340\" src=\"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/12\/novo_citius-06-scaled.webp\" class=\"attachment-full size-full wp-image-14625\" alt=\"\" srcset=\"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/12\/novo_citius-06-scaled.webp 2560w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/12\/novo_citius-06-300x157.webp 300w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/12\/novo_citius-06-1024x536.webp 1024w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/12\/novo_citius-06-768x402.webp 768w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/12\/novo_citius-06-1536x804.webp 1536w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/12\/novo_citius-06-2048x1072.webp 2048w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/12\/novo_citius-06-18x9.webp 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-90a94e7 e-con-full e-flex e-con e-child\" data-id=\"90a94e7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2946b50 e-con-full e-flex e-con e-child\" data-id=\"2946b50\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-894d842 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"894d842\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"510\" height=\"527\" viewbox=\"0 0 510 527\" fill=\"none\"><path opacity=\"0.4\" d=\"M92.708 153.492C92.708 132.264 109.917 115.055 131.146 115.055H378.854C400.082 115.055 417.291 132.264 417.291 153.492V333.693C417.291 354.923 400.082 372.131 378.854 372.131H307.982L265.292 429.633C262.875 432.888 259.06 434.808 255.005 434.808C250.951 434.808 247.134 432.888 244.717 429.633L202.03 372.131H131.146C109.917 372.131 92.708 354.923 92.708 333.693V153.492ZM131.146 140.68C124.069 140.68 118.333 146.416 118.333 153.492V333.693C118.333 340.769 124.069 346.506 131.146 346.506H208.475C212.53 346.506 216.345 348.426 218.762 351.682L255.005 400.501L291.249 351.682C293.666 348.426 297.481 346.506 301.536 346.506H378.854C385.93 346.506 391.666 340.769 391.666 333.693V153.492C391.666 146.416 385.93 140.68 378.854 140.68H131.146Z\" fill=\"#1D4859\"><\/path><path d=\"M156.771 225.963C156.771 218.887 162.507 213.15 169.583 213.15H340.416C347.492 213.15 353.229 218.887 353.229 225.963C353.229 233.04 347.492 238.775 340.416 238.775H169.583C162.507 238.775 156.771 233.04 156.771 225.963Z\" fill=\"#1D4859\"><\/path><path d=\"M169.583 264.399C162.507 264.399 156.771 270.136 156.771 277.212C156.771 284.29 162.507 290.024 169.583 290.024H255C262.076 290.024 267.812 284.29 267.812 277.212C267.812 270.136 262.076 264.399 255 264.399H169.583Z\" fill=\"#1D4859\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16178ab elementor-widget elementor-widget-text-editor\" data-id=\"16178ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Gest\u00e3o centralizada de comunica\u00e7\u00f5es.<\/strong><br \/>Os emails e anexos podem ser associados automaticamente a contactos e entidades, ou ligados manualmente a qualquer registo da aplica\u00e7\u00e3o, como processos e contratos.<\/p><p data-start=\"1846\" data-end=\"1995\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ea34cac e-con-full e-flex e-con e-child\" data-id=\"ea34cac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c87e0d elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4c87e0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"510\" height=\"527\" viewbox=\"0 0 510 527\" fill=\"none\"><path d=\"M115 182.688V131.438C115 110.209 132.209 93 153.438 93H226.042C238.14 93 249.529 98.7029 256.788 108.382L279.861 139.128L280.828 140.279C283.232 142.8 286.578 144.25 290.104 144.25H418.229C439.457 144.25 456.667 161.459 456.667 182.688C456.667 189.764 450.93 195.5 443.854 195.5C437.223 195.5 431.768 190.462 431.109 184.005L430.975 181.37C430.316 174.913 424.861 169.875 418.229 169.875H290.104C278.759 169.875 268.036 164.866 260.759 156.262L259.358 154.493L236.285 123.747C233.865 120.524 230.073 118.625 226.042 118.625H153.438C146.362 118.625 140.625 124.361 140.625 131.438V182.688C140.625 189.764 134.889 195.5 127.813 195.5C120.737 195.5 115 189.764 115 182.688Z\" fill=\"#1D4859\"><\/path><path opacity=\"0.4\" d=\"M456.667 182.688V336.438C456.667 357.665 439.457 374.875 418.229 374.875H153.438C132.209 374.875 115 357.665 115 336.438V182.688C115 189.764 120.737 195.5 127.813 195.5C134.889 195.5 140.625 189.764 140.625 182.688V336.438C140.625 343.513 146.362 349.25 153.438 349.25H418.229C425.305 349.25 431.042 343.513 431.042 336.438V182.688L431.109 184.005C431.768 190.462 437.223 195.5 443.854 195.5C450.93 195.5 456.667 189.764 456.667 182.688Z\" fill=\"#1D4859\"><\/path><path d=\"M79.6251 156.813C79.6251 149.736 73.8885 144 66.8126 144C59.7367 144 54.0001 149.736 54.0001 156.813V354.415C54.0001 399.23 90.3295 435.561 135.146 435.561H260.86C267.936 435.561 273.672 429.824 273.672 422.748C273.672 415.671 267.936 409.936 260.86 409.936H135.146C104.483 409.936 79.6251 385.078 79.6251 354.415V156.813Z\" fill=\"#1D4859\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c30b47 elementor-widget elementor-widget-text-editor\" data-id=\"1c30b47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Documentos sempre acess\u00edveis e organizados. <\/strong><br \/>Aceda a documentos guardados no OneDrive e no SharePoint sem duplicar ficheiros nem perder o contexto jur\u00eddico.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ba2759 e-con-full e-flex e-con e-child\" data-id=\"7ba2759\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c91ea3 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"3c91ea3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"510\" height=\"527\" viewbox=\"0 0 510 527\" fill=\"none\"><path opacity=\"0.4\" d=\"M153.541 161.5C164.265 161.5 174.463 166.164 181.472 174.281L242.7 245.181L303.928 174.281L306.698 171.398C313.492 165.067 322.476 161.5 331.859 161.5H406.7L407.964 161.564C414.165 162.197 419 167.434 419 173.8C419 180.166 414.165 185.403 407.964 186.036L406.7 186.1H331.859C328.729 186.1 325.732 187.288 323.467 189.399L322.553 190.36L258.939 264L322.553 337.639L323.467 338.6C325.732 340.713 328.729 341.9 331.859 341.9H406.7L407.964 341.964C414.165 342.597 419 347.834 419 354.2C419 360.566 414.165 365.803 407.964 366.436L406.7 366.5H331.859C322.475 366.5 313.492 362.933 306.698 356.603L303.928 353.719L242.7 282.803L181.472 353.719C174.463 361.836 164.265 366.5 153.541 366.5H103.3C96.507 366.5 91 360.993 91 354.2C91.001 347.407 96.5074 341.9 103.3 341.9H153.541C157.115 341.9 160.51 340.345 162.846 337.639L226.444 264L162.846 190.36C160.51 187.657 157.114 186.1 153.541 186.1H103.3C96.507 186.1 91 180.593 91 173.8C91.001 167.008 96.5074 161.5 103.3 161.5H153.541Z\" fill=\"#1D4859\"><\/path><path d=\"M361.105 308.604C365.607 304.101 372.737 303.816 377.569 307.755L378.497 308.604L415.397 345.504L416.246 346.433C420.187 351.264 419.9 358.393 415.397 362.897L378.497 399.797C373.693 404.6 365.907 404.6 361.105 399.797C356.301 394.993 356.301 387.208 361.105 382.404L389.308 354.201L361.105 325.997L360.255 325.068C356.316 320.238 356.603 313.108 361.105 308.604ZM361.105 128.204C365.607 123.701 372.737 123.416 377.569 127.355L378.497 128.204L415.397 165.104L416.246 166.033C420.187 170.864 419.9 177.994 415.397 182.497L378.497 219.397C373.693 224.201 365.907 224.201 361.105 219.397C356.301 214.594 356.301 206.808 361.105 202.004L389.308 173.801L361.105 145.597L360.255 144.668C356.316 139.838 356.603 132.707 361.105 128.204Z\" fill=\"#1D4859\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12ef9b4 elementor-widget elementor-widget-text-editor\" data-id=\"12ef9b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Atualiza\u00e7\u00f5es externas sobre controlo.<\/strong><br \/>Traga notifica\u00e7\u00f5es e movimentos relevantes para dentro do Rolling Legal, com mais visibilidade sobre prazos, hist\u00f3rico e acompanhamento.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e28f9b e-flex e-con-boxed e-con e-parent\" data-id=\"5e28f9b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3944fd0 elementor-widget elementor-widget-heading\" data-id=\"3944fd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Integra\u00e7\u00e3o perfeita com ferramentas<\/br>\nque fazem parte do seu dia-a-dia.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-13e5495 e-flex e-con-boxed e-con e-parent\" data-id=\"13e5495\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1a612c1 e-con-full e-flex e-con e-child\" data-id=\"1a612c1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-030f6a0 elementor-widget elementor-widget-image\" data-id=\"030f6a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1699\" src=\"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/calendario_tarefas_2-scaled.png\" class=\"attachment-full size-full wp-image-12726\" alt=\"\" srcset=\"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/calendario_tarefas_2-scaled.png 2560w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/calendario_tarefas_2-300x199.png 300w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/calendario_tarefas_2-1024x679.png 1024w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/calendario_tarefas_2-768x510.png 768w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/calendario_tarefas_2-1536x1019.png 1536w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/calendario_tarefas_2-2048x1359.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-617d210 e-con-full e-flex e-con e-child\" data-id=\"617d210\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f3a4c0 elementor-widget elementor-widget-heading\" data-id=\"5f3a4c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Microsoft 365 ligada \u00e0 opera\u00e7\u00e3o jur\u00eddica<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-074819f elementor-widget elementor-widget-text-editor\" data-id=\"074819f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Conecte o email, contactos, calend\u00e1rio e documentos ao trabalho jur\u00eddico do dia a dia, com menos mudan\u00e7a de contexto entre ferramentas e maior visibilidade sobre a informa\u00e7\u00e3o relevante para cada assunto.<\/p><ul><li>Menos plataformas abertas em simult\u00e2neo.<\/li><li>Informa\u00e7\u00e3o mais f\u00e1cil de relacionar com pessoas, entidades e registos.<\/li><li>Mais hist\u00f3rico e rastreabilidade no trabalho da equipa.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3faf40a elementor-widget elementor-widget-text-editor\" data-id=\"3faf40a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Os emails, contactos, calend\u00e1rios e documentos continuam no ecossistema Microsoft. O contexto jur\u00eddico \u00e9 que passa a estar reunido num s\u00f3 lugar.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-932ebdb e-flex e-con-boxed e-con e-parent\" data-id=\"932ebdb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b43574a e-con-full e-flex e-con e-child\" data-id=\"b43574a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f247502 elementor-widget elementor-widget-heading\" data-id=\"f247502\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Emails organizados, n\u00e3o apenas arquivados\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc1360f elementor-widget elementor-widget-text-editor\" data-id=\"bc1360f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Com a integra\u00e7\u00e3o de email, as comunica\u00e7\u00f5es deixam de ficar dispersas pela caixa de entrada.<\/p><ul><li>Associa\u00e7\u00e3o de emails e anexos a contactos e entidades.<\/li><li>Liga\u00e7\u00e3o manual a processos, contratos e outros registos da aplica\u00e7\u00e3o.<\/li><li>Hist\u00f3rico de comunica\u00e7\u00f5es mais claro e pesquis\u00e1vel.<\/li><li data-section-id=\"rmq3nm\" data-start=\"3273\" data-end=\"3318\">Menos tempo perdido \u00e0 procura de informa\u00e7\u00e3o.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c90f2c elementor-widget elementor-widget-text-editor\" data-id=\"5c90f2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>O email deixa de viver \u00e0 parte da opera\u00e7\u00e3o jur\u00eddica.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8e1ae02 e-con-full e-flex e-con e-child\" data-id=\"8e1ae02\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-810771a elementor-widget elementor-widget-image\" data-id=\"810771a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1426\" src=\"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/chat_email_2-scaled.png\" class=\"attachment-full size-full wp-image-12760\" alt=\"\" srcset=\"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/chat_email_2-scaled.png 2560w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/chat_email_2-300x167.png 300w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/chat_email_2-1024x570.png 1024w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/chat_email_2-768x428.png 768w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/chat_email_2-1536x856.png 1536w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/chat_email_2-2048x1141.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0856338 e-flex e-con-boxed e-con e-parent\" data-id=\"0856338\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1e3ce43 e-con-full e-flex e-con e-child\" data-id=\"1e3ce43\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-31e9dc3 elementor-widget elementor-widget-image\" data-id=\"31e9dc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2330\" src=\"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/08\/gestao_documentos_3-scaled.png\" class=\"attachment-full size-full wp-image-13684\" alt=\"\" srcset=\"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/08\/gestao_documentos_3-scaled.png 2560w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/08\/gestao_documentos_3-300x273.png 300w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/08\/gestao_documentos_3-1024x932.png 1024w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/08\/gestao_documentos_3-768x699.png 768w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/08\/gestao_documentos_3-1536x1398.png 1536w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/08\/gestao_documentos_3-2048x1864.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9e4d372 e-con-full e-flex e-con e-child\" data-id=\"9e4d372\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c19efcd elementor-widget elementor-widget-heading\" data-id=\"c19efcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Documentos com contexto jur\u00eddico<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-321ae9d elementor-widget elementor-widget-text-editor\" data-id=\"321ae9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O Rolling Legal integra-se com OneDrive e SharePoint para permitir trabalhar sobre documentos armazenados no reposit\u00f3rio original, com acesso facilitado a partir do contexto jur\u00eddico.<\/p><ul><li>Acesso aos documentos onde j\u00e1 est\u00e3o guardados.<\/li><li>Liga\u00e7\u00e3o ao registo relevante sem criar c\u00f3pias desnecess\u00e1rias.<\/li><li>Consulta da vers\u00e3o mais atual no reposit\u00f3rio original.<\/li><li>Colabora\u00e7\u00e3o com base na estrutura documental j\u00e1 existente.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d156f64 elementor-widget elementor-widget-text-editor\" data-id=\"d156f64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Os documentos continuam no seu ambiente Microsoft. O contexto jur\u00eddico \u00e9 que passa a estar centralizado.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63aea64 e-flex e-con-boxed e-con e-parent\" data-id=\"63aea64\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-60baab2 e-con-full e-flex e-con e-child\" data-id=\"60baab2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2dfca02 elementor-widget elementor-widget-heading\" data-id=\"2dfca02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Integra\u00e7\u00e3o com o Citius<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa14a8d elementor-widget elementor-widget-text-editor\" data-id=\"fa14a8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O Rolling Legal integra-se com o Citius atrav\u00e9s de add-on parceiro, permitindo receber notifica\u00e7\u00f5es, alertas e atualiza\u00e7\u00f5es diretamente na plataforma.<\/p><ul><li>Notifica\u00e7\u00f5es do Citius associadas ao processo.<\/li><li>Redu\u00e7\u00e3o de acessos manuais \u00e0 plataforma.<\/li><li><span style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\">Maior controlo de prazos e movimentos processuais.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4757711 elementor-widget elementor-widget-text-editor\" data-id=\"4757711\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>O Citius passa a fazer parte do fluxo de trabalho, n\u00e3o uma tarefa paralela.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67f9c3c e-con-full e-flex e-con e-child\" data-id=\"67f9c3c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf60114 elementor-widget elementor-widget-image\" data-id=\"bf60114\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1629\" src=\"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/departamento_juridico_3-copia-scaled.png\" class=\"attachment-full size-full wp-image-12847\" alt=\"\" srcset=\"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/departamento_juridico_3-copia-scaled.png 2560w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/departamento_juridico_3-copia-300x191.png 300w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/departamento_juridico_3-copia-1024x652.png 1024w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/departamento_juridico_3-copia-768x489.png 768w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/departamento_juridico_3-copia-1536x977.png 1536w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/departamento_juridico_3-copia-2048x1303.png 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-02a0848 e-flex e-con-boxed e-con e-parent\" data-id=\"02a0848\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a27f54c elementor-widget elementor-widget-heading\" data-id=\"a27f54c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tudo ligado \u00e0 opera\u00e7\u00e3o jur\u00eddica\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0711fcc elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0711fcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>O Rolling Legal foi desenhado para ligar processos, comunica\u00e7\u00f5es, documentos e informa\u00e7\u00e3o externa num s\u00f3 fluxo de trabalho, com mais contexto, menos dispers\u00e3o e maior controlo.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a73bba e-con-full e-flex e-con e-child\" data-id=\"9a73bba\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6ad958a e-con-full e-flex e-con e-child\" data-id=\"6ad958a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;background_motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9494cf8 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"9494cf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"410\" height=\"410\" viewbox=\"0 0 410 410\" fill=\"none\"><g clip-path=\"url(#clip0_1713_2835)\"><rect width=\"410\" height=\"410\" rx=\"30\" fill=\"#1D4859\"><\/rect><path opacity=\"0.4\" d=\"M113.166 107.136C113.166 102.069 109.058 97.9609 103.991 97.9609C98.9241 97.9609 94.8164 102.069 94.8164 107.136V284.514C94.8164 299.714 107.139 312.038 122.341 312.038H299.725C304.792 312.038 308.9 307.93 308.9 302.863C308.9 297.796 304.792 293.689 299.725 293.689H122.341C117.274 293.689 113.166 289.581 113.166 284.514V250.626V224.676V107.136Z\" fill=\"white\"><\/path><path d=\"M161.109 176.727L113.164 224.672V250.622L167.596 196.19L209.462 238.055C211.182 239.776 213.516 240.743 215.949 240.743C218.382 240.743 220.716 239.776 222.436 238.055L262.745 197.747L277.902 212.904C280.527 215.529 284.476 216.315 287.906 214.892C291.335 213.469 293.569 210.12 293.565 206.407L293.516 163.165C293.511 158.103 289.406 154.001 284.344 154.001L241.142 153.992C237.43 153.991 234.085 156.227 232.664 159.655C231.243 163.084 232.028 167.03 234.652 169.654L249.77 184.772L215.949 218.592L174.084 176.727C172.363 175.006 170.03 174.04 167.596 174.04C165.163 174.04 162.829 175.006 161.109 176.727Z\" fill=\"white\"><\/path><\/g><defs><clippath id=\"clip0_1713_2835\"><rect width=\"410\" height=\"410\" fill=\"white\"><\/rect><\/clippath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acc7fb0 elementor-widget elementor-widget-heading\" data-id=\"acc7fb0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Mais produtividade para equipas jur\u00eddicas<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a806f91 elementor-widget elementor-widget-text-editor\" data-id=\"a806f91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Com informa\u00e7\u00e3o centralizada e processos estruturados, a equipa trabalha com mais foco, menos interrup\u00e7\u00f5es e maior previsibilidade no dia a dia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d34589 e-con-full e-flex e-con e-child\" data-id=\"4d34589\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;background_motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7c770e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"d7c770e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"410\" height=\"410\" viewbox=\"0 0 410 410\" fill=\"none\"><g clip-path=\"url(#clip0_1713_2830)\"><rect width=\"410\" height=\"410\" rx=\"30\" fill=\"#1D4859\"><\/rect><path opacity=\"0.4\" d=\"M166.113 299.616V316.304H132.738C118.914 316.304 107.707 305.096 107.707 291.273V178.589C107.707 171.952 110.342 165.588 115.033 160.894L174.748 101.142C179.443 96.4441 185.812 93.8047 192.454 93.8047H249.55C263.374 93.8047 274.581 105.012 274.581 118.836V180.023H257.894V118.836C257.894 114.228 254.158 110.492 249.55 110.492H193.903L193.935 154.974C193.945 168.805 182.736 180.023 168.904 180.023H124.394V291.273C124.394 295.881 128.13 299.616 132.738 299.616H166.113ZM177.225 122.271L136.185 163.336H168.904C173.514 163.336 177.251 159.596 177.248 154.986L177.225 122.271Z\" fill=\"white\"><\/path><path d=\"M283.47 208.811C275.868 201.209 263.541 201.209 255.937 208.811L198.553 266.196C194.516 270.233 191.981 275.528 191.367 281.204L189.263 300.638C188.992 303.15 189.873 305.649 191.658 307.435C193.445 309.222 195.945 310.102 198.457 309.83L217.891 307.728C223.566 307.114 228.861 304.578 232.897 300.541L290.283 243.156C297.886 235.554 297.886 223.227 290.283 215.623L283.47 208.811ZM258.141 230.208L268.887 240.954L221.098 288.742C219.752 290.087 217.988 290.933 216.095 291.137L206.97 292.125L207.956 282.998C208.161 281.107 209.007 279.341 210.353 277.996L258.141 230.208Z\" fill=\"white\"><\/path><\/g><defs><clippath id=\"clip0_1713_2830\"><rect width=\"410\" height=\"410\" fill=\"white\"><\/rect><\/clippath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6eae765 elementor-widget elementor-widget-heading\" data-id=\"6eae765\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Automatiza\u00e7\u00e3o que reduz trabalho manual<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ebb45d elementor-widget elementor-widget-text-editor\" data-id=\"0ebb45d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Automatize tarefas repetitivas, sincronize informa\u00e7\u00e3o e elimine registos duplicados. Mais efici\u00eancia operacional, menos tempo gasto em tarefas administrativas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05ae393 e-con-full e-flex e-con e-child\" data-id=\"05ae393\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;background_motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3054d17 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"3054d17\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"410\" height=\"410\" viewbox=\"0 0 410 410\" fill=\"none\"><g clip-path=\"url(#clip0_1713_2846)\"><rect width=\"410\" height=\"410\" rx=\"30\" fill=\"#1D4859\"><\/rect><path d=\"M90.2643 176.028C89.0008 180.744 91.7992 185.59 96.5147 186.854C101.23 188.117 106.077 185.319 107.341 180.604C112.712 160.557 124.549 142.842 141.014 130.208C157.479 117.574 177.654 110.726 198.408 110.726C219.161 110.726 239.336 117.574 255.801 130.208C270.157 141.224 280.995 156.101 287.095 173.019L267.352 161.902C263.099 159.506 257.708 161.013 255.313 165.267C252.918 169.521 254.425 174.911 258.678 177.306L294.987 197.751C297.03 198.901 299.446 199.194 301.705 198.562C303.962 197.93 305.877 196.429 307.027 194.385L327.471 158.073C329.866 153.819 328.358 148.429 324.105 146.034C319.851 143.639 314.46 145.146 312.066 149.4L303.099 165.326C295.75 145.937 283.13 128.895 266.564 116.183C247.011 101.179 223.053 93.0469 198.408 93.0469C173.762 93.0469 149.805 101.179 130.252 116.183C110.699 131.186 96.6432 152.222 90.2643 176.028Z\" fill=\"white\"><\/path><path opacity=\"0.4\" d=\"M306.589 233.98C307.853 229.264 305.053 224.418 300.338 223.154C295.622 221.891 290.776 224.689 289.513 229.404C284.141 249.452 272.304 267.166 255.839 279.801C239.373 292.435 219.2 299.283 198.446 299.283C177.691 299.283 157.517 292.435 141.052 279.801C126.721 268.804 115.897 253.959 109.789 237.078L129.385 248.112C133.639 250.507 139.029 249.001 141.425 244.747C143.82 240.493 142.313 235.103 138.06 232.708L101.751 212.262C99.708 211.112 97.2919 210.821 95.034 211.451C92.776 212.083 90.8614 213.586 89.7113 215.628L69.2673 251.94C66.8723 256.195 68.3793 261.584 72.6332 263.979C76.8873 266.374 82.2773 264.868 84.6723 260.613L93.709 244.563C101.051 264.002 113.689 281.088 130.289 293.826C149.842 308.829 173.799 316.961 198.446 316.961C223.091 316.961 247.048 308.829 266.601 293.826C286.154 278.822 300.209 257.786 306.589 233.98Z\" fill=\"white\"><\/path><\/g><defs><clippath id=\"clip0_1713_2846\"><rect width=\"410\" height=\"410\" fill=\"white\"><\/rect><\/clippath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-306f8ff elementor-widget elementor-widget-heading\" data-id=\"306f8ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Prazos e compromissos sempre sob controlo<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbd0fc0 elementor-widget elementor-widget-text-editor\" data-id=\"fbd0fc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gest\u00e3o centralizada de prazos, dilig\u00eancias e eventos processuais, com alertas autom\u00e1ticos e visibilidade total para a equipa.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-280fbb6 e-flex e-con-boxed e-con e-parent\" data-id=\"280fbb6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1489bd7 e-con-full e-flex e-con e-child\" data-id=\"1489bd7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-80ca0f7 e-con-full e-flex e-con e-child\" data-id=\"80ca0f7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d0fad1 elementor-widget elementor-widget-heading\" data-id=\"1d0fad1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default translation-block\">Teste na pr\u00e1tica, <br>agende uma demo!<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e617b8f elementor-widget elementor-widget-text-editor\" data-id=\"e617b8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>N\u00e3o gosta de formul\u00e1rios? Envie-nos um email.<br \/>equipamarketing@rolling-space.pt<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc8b4a0 elementor-widget elementor-widget-button\" data-id=\"fc8b4a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rolling-legal.com\/es\/agendar-demo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Agendar Demo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-56a3029 e-con-full e-flex e-con e-child\" data-id=\"56a3029\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3023473 elementor-widget elementor-widget-image\" data-id=\"3023473\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1446\" src=\"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/09\/graficos_PT-07-scaled.webp\" class=\"attachment-full size-full wp-image-14214\" alt=\"\" srcset=\"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/09\/graficos_PT-07-scaled.webp 2560w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/09\/graficos_PT-07-300x169.webp 300w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/09\/graficos_PT-07-1024x578.webp 1024w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/09\/graficos_PT-07-768x434.webp 768w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/09\/graficos_PT-07-1536x868.webp 1536w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/09\/graficos_PT-07-2048x1157.webp 2048w, https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/09\/graficos_PT-07-18x10.webp 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Conecte-se e simplifique! Centralize comunica\u00e7\u00f5es, documentos e informa\u00e7\u00e3o relevante numa s\u00f3 plataforma, sem obrigar a equipa a mudar a forma como j\u00e1 trabalha. O Rolling Legal ajuda a reduzir contexto disperso, melhorar a organiza\u00e7\u00e3o e aumentar o controlo da opera\u00e7\u00e3o jur\u00eddica. Integra\u00e7\u00f5es que poupam tempo e aumentam produtividade. Gest\u00e3o centralizada de comunica\u00e7\u00f5es.Os emails e anexos [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"nf_dc_page":"","inline_featured_image":false,"footnotes":""},"class_list":["post-12886","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Integra\u00e7\u00f5es - Rolling Legal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rolling-legal.com\/es\/integracoes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Integra\u00e7\u00f5es - Rolling Legal\" \/>\n<meta property=\"og:description\" content=\"Conecte-se e simplifique! Centralize comunica\u00e7\u00f5es, documentos e informa\u00e7\u00e3o relevante numa s\u00f3 plataforma, sem obrigar a equipa a mudar a forma como j\u00e1 trabalha. O Rolling Legal ajuda a reduzir contexto disperso, melhorar a organiza\u00e7\u00e3o e aumentar o controlo da opera\u00e7\u00e3o jur\u00eddica. Integra\u00e7\u00f5es que poupam tempo e aumentam produtividade. Gest\u00e3o centralizada de comunica\u00e7\u00f5es.Os emails e anexos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rolling-legal.com\/es\/integracoes\/\" \/>\n<meta property=\"og:site_name\" content=\"Rolling Legal\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T10:07:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/12\/novo_citius-06-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rolling-legal.com\\\/integracoes\\\/\",\"url\":\"https:\\\/\\\/rolling-legal.com\\\/integracoes\\\/\",\"name\":\"Integra\u00e7\u00f5es - Rolling Legal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rolling-legal.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rolling-legal.com\\\/integracoes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rolling-legal.com\\\/integracoes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rolling-legal.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/novo_citius-06-scaled.webp\",\"datePublished\":\"2025-07-24T14:20:55+00:00\",\"dateModified\":\"2026-04-16T10:07:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rolling-legal.com\\\/integracoes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rolling-legal.com\\\/integracoes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rolling-legal.com\\\/integracoes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rolling-legal.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/novo_citius-06-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/rolling-legal.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/novo_citius-06-scaled.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rolling-legal.com\\\/integracoes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rolling-legal.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Integra\u00e7\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rolling-legal.com\\\/#website\",\"url\":\"https:\\\/\\\/rolling-legal.com\\\/\",\"name\":\"Rolling Legal\",\"description\":\"Plataforma Cloud de Legal\",\"publisher\":{\"@id\":\"https:\\\/\\\/rolling-legal.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rolling-legal.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rolling-legal.com\\\/#organization\",\"name\":\"Rolling Legal\",\"url\":\"https:\\\/\\\/rolling-legal.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/rolling-legal.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rolling-legal.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logotipo_web.png\",\"contentUrl\":\"https:\\\/\\\/rolling-legal.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/logotipo_web.png\",\"width\":2042,\"height\":827,\"caption\":\"Rolling Legal\"},\"image\":{\"@id\":\"https:\\\/\\\/rolling-legal.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Integra\u00e7\u00f5es - Rolling Legal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rolling-legal.com\/es\/integracoes\/","og_locale":"es_ES","og_type":"article","og_title":"Integra\u00e7\u00f5es - Rolling Legal","og_description":"Conecte-se e simplifique! Centralize comunica\u00e7\u00f5es, documentos e informa\u00e7\u00e3o relevante numa s\u00f3 plataforma, sem obrigar a equipa a mudar a forma como j\u00e1 trabalha. O Rolling Legal ajuda a reduzir contexto disperso, melhorar a organiza\u00e7\u00e3o e aumentar o controlo da opera\u00e7\u00e3o jur\u00eddica. Integra\u00e7\u00f5es que poupam tempo e aumentam produtividade. Gest\u00e3o centralizada de comunica\u00e7\u00f5es.Os emails e anexos [&hellip;]","og_url":"https:\/\/rolling-legal.com\/es\/integracoes\/","og_site_name":"Rolling Legal","article_modified_time":"2026-04-16T10:07:29+00:00","og_image":[{"width":2560,"height":1340,"url":"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/12\/novo_citius-06-scaled.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rolling-legal.com\/integracoes\/","url":"https:\/\/rolling-legal.com\/integracoes\/","name":"Integra\u00e7\u00f5es - Rolling Legal","isPartOf":{"@id":"https:\/\/rolling-legal.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rolling-legal.com\/integracoes\/#primaryimage"},"image":{"@id":"https:\/\/rolling-legal.com\/integracoes\/#primaryimage"},"thumbnailUrl":"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/12\/novo_citius-06-scaled.webp","datePublished":"2025-07-24T14:20:55+00:00","dateModified":"2026-04-16T10:07:29+00:00","breadcrumb":{"@id":"https:\/\/rolling-legal.com\/integracoes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rolling-legal.com\/integracoes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rolling-legal.com\/integracoes\/#primaryimage","url":"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/12\/novo_citius-06-scaled.webp","contentUrl":"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/12\/novo_citius-06-scaled.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/rolling-legal.com\/integracoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rolling-legal.com\/"},{"@type":"ListItem","position":2,"name":"Integra\u00e7\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/rolling-legal.com\/#website","url":"https:\/\/rolling-legal.com\/","name":"Rolling Legal","description":"Plataforma Cloud de Legal","publisher":{"@id":"https:\/\/rolling-legal.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rolling-legal.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/rolling-legal.com\/#organization","name":"Rolling Legal","url":"https:\/\/rolling-legal.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/rolling-legal.com\/#\/schema\/logo\/image\/","url":"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/logotipo_web.png","contentUrl":"https:\/\/rolling-legal.com\/wp-content\/uploads\/2025\/07\/logotipo_web.png","width":2042,"height":827,"caption":"Rolling Legal"},"image":{"@id":"https:\/\/rolling-legal.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rolling-legal.com\/es\/wp-json\/wp\/v2\/pages\/12886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rolling-legal.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rolling-legal.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rolling-legal.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/rolling-legal.com\/es\/wp-json\/wp\/v2\/comments?post=12886"}],"version-history":[{"count":5,"href":"https:\/\/rolling-legal.com\/es\/wp-json\/wp\/v2\/pages\/12886\/revisions"}],"predecessor-version":[{"id":15163,"href":"https:\/\/rolling-legal.com\/es\/wp-json\/wp\/v2\/pages\/12886\/revisions\/15163"}],"wp:attachment":[{"href":"https:\/\/rolling-legal.com\/es\/wp-json\/wp\/v2\/media?parent=12886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}